{
    "id": 2018,
    "date": "2021-01-11T15:50:44",
    "date_gmt": "2021-01-11T14:50:44",
    "guid": {
        "rendered": "https:\/\/www.bbmri.it\/?p=2018"
    },
    "modified": "2021-02-11T15:50:35",
    "modified_gmt": "2021-02-11T14:50:35",
    "slug": "gruppo-di-lavoro-elsi-2021-di-bbmri-it",
    "status": "publish",
    "type": "post",
    "link": "http:\/\/www.bbmri.it\/en\/gruppo-di-lavoro-elsi-2021-di-bbmri-it\/",
    "title": {
        "rendered": "Gruppo di lavoro ELSI 2021 di BBMRI.it"
    },
    "content": {
        "rendered": "<div data-elementor-type=\"wp-post\" data-elementor-id=\"2018\" class=\"elementor elementor-2018\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-690234e1 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"690234e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4695f0b5\" data-id=\"4695f0b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-61352200 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61352200\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2aa77202\" data-id=\"2aa77202\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b641dda elementor-widget elementor-widget-heading\" data-id=\"4b641dda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Per una buona pratica del biobancaggio traslazionale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74ff1140 elementor-widget elementor-widget-heading\" data-id=\"74ff1140\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gruppo di lavoro ELSI 2021 di BBMRI.it<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f174758 elementor-widget elementor-widget-text-editor\" data-id=\"7f174758\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"uk-card uk-card-default uk-card-body uk-box-shadow-large\" align=\"justify\"><div class=\"translation-block\"><div>Grande \u00e8 la sfida del biobancaggio traslazionale, ovvero della messa a disposizione per finalit\u00e0 scientifiche, in qualit\u00e0 e nel rispetto dei diritti del paziente-cittadino, del materiale biologico inizialmente raccolto per scopi clinici (diagnostici, terapeutici, o ad altro titolo detenuto).<br \/><br \/>Non solo il Decreto legislativo del 14 maggio 2019, ci sprona a promuovere e ad indirizzare la semplificazione del riuso per scopi scientifici di questi materiali, ma il confronto aperto con la comunit\u00e0 allargata di BBMRI.it e le richieste pervenute all\u2019<em>help-desk<span>\u00a0<\/span><\/em>ELSI hanno evidenziato come proprio qui si giochi la messa a fattore comune del biobanking come diritto di salute e di ricerca, come processo traslazionale frutto di un grande e consapevole lavoro di squadra tra clinici, pazienti-cittadini, biobancari, ricercatori.<br \/><br \/>Il biobanking traslazionale sar\u00e0 il tema del<span>\u00a0<\/span><strong>gruppo di lavoro ELSI 2021 di BBMRI.it \u201cPer una buona pratica del biobancaggio traslazionale\u201d.<\/strong><span>\u00a0<\/span>I principali obiettivi di questo gruppo di lavoro sono<\/div><ul><li>favorire e supportare la buona pratica del biobancaggio traslazionale grazie a<\/li><\/ul><ul><li>un dialogo precoce con i cittadini, i professionisti della salute e i comitati etici<\/li><li>la co-produzione di strumenti ELSI e in qualit\u00e0,<\/li><\/ul><ul><li>condivisione di un documento collegiale \u201cPer la buona pratica del biobancaggio traslazionale\u201d,<\/li><\/ul><div>attraverso l\u2019analisi proattiva di<span>\u00a0<\/span><em>use case<span>\u00a0<\/span><\/em>emblematici, delle problematiche che presentano e la discussione dei requisiti in termini di qualit\u00e0, sostenibilit\u00e0 ed eticit\u00e0 che devono essere previsti e rispettati sin dal principio del processo al fine di un biobancaggio per scopi di ricerca.<br \/>Se sei professionista della salute, biobancar@, ricercatore, rappresentante di pazienti-cittadini, esperto ELSI, membro di un comitato etico, puoi partecipare e a contribuire ai lavori, iscrivendoti al gruppo di lavoro ELSI 2021 direttamente al seguente<span>\u00a0<\/span><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdxDOmRK879Z19JGqMS-0HVnV3ZedG-Hx3c9zl4fzdl8yjgYQ\/viewform\" target=\"_blank\" rel=\"noopener\">link<\/a><br \/>\u00a0<br \/>Le attivit\u00e0 si svolgeranno in una prima fase, tra gennaio e marzo, con cadenza bisettimanale per facilitare il confronto e il dialogo con il gruppo di lavoro ISS incaricato della stesura delle linee di indirizzo la semplificazione del riuso dei suddetti materiali. Le attivit\u00e0 del gruppo ELSI 2021 si finalizzeranno in primavera, con la pubblicazione del documento di buona pratica condiviso e di una matrice per il consenso al biobanking traslazionale.<span>\u00a0<\/span><strong>La proposta di programma<\/strong>,<span>\u00a0<\/span><strong><a href=\"http:\/\/bit.ly\/2021-ELSI-BBMRI\" target=\"_blank\" rel=\"noopener\">in allegato<\/a><\/strong>, sar\u00e0 dibattuta dai partecipanti a inizio lavori,<strong><span>\u00a0<\/span>il 28 gennaio 2021<\/strong>, sar\u00e0 inoltre predisposta previamente una cartella digitale collaborativa per la condivisione progressiva della documentazione.<\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3db9815f elementor-button-warning elementor-align-right elementor-widget elementor-widget-button\" data-id=\"3db9815f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdxDOmRK879Z19JGqMS-0HVnV3ZedG-Hx3c9zl4fzdl8yjgYQ\/viewform\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tag\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Iscriviti al WG ELSI 2021<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d35df6b elementor-button-info elementor-align-right elementor-widget elementor-widget-button\" data-id=\"d35df6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/bit.ly\/2021-ELSI-BBMRI\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-link\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scarica il programma dei lavori<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>Per una buona pratica del biobancaggio traslazionale Gruppo di lavoro ELSI 2021 di BBMRI.it Grande \u00e8 la sfida del biobancaggio traslazionale, ovvero della messa a disposizione per finalit\u00e0 scientifiche, in qualit\u00e0 e nel rispetto dei diritti del paziente-cittadino, del materiale biologico inizialmente raccolto per scopi clinici (diagnostici, terapeutici, o ad [&hellip;]<\/p>",
        "protected": false
    },
    "author": 1,
    "featured_media": 22,
    "comment_status": "closed",
    "ping_status": "open",
    "sticky": false,
    "template": "",
    "format": "standard",
    "meta": {
        "footnotes": ""
    },
    "categories": [
        18,
        2
    ],
    "tags": [
        43,
        48,
        32,
        3
    ],
    "class_list": [
        "post-2018",
        "post",
        "type-post",
        "status-publish",
        "format-standard",
        "has-post-thumbnail",
        "hentry",
        "category-archiviati",
        "category-news",
        "tag-bbmri-it",
        "tag-biobancaggio",
        "tag-elsi",
        "tag-news"
    ],
    "publishpress_future_action": {
        "enabled": false,
        "date": "2026-07-22 03:08:06",
        "action": "change-status",
        "newStatus": "draft",
        "terms": [],
        "taxonomy": "category",
        "extraData": []
    },
    "publishpress_future_workflow_manual_trigger": {
        "enabledWorkflows": []
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/www.bbmri.it\/en\/wp-json\/wp\/v2\/posts\/2018",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/www.bbmri.it\/en\/wp-json\/wp\/v2\/posts"
            }
        ],
        "about": [
            {
                "href": "https:\/\/www.bbmri.it\/en\/wp-json\/wp\/v2\/types\/post"
            }
        ],
        "author": [
            {
                "embeddable": true,
                "href": "https:\/\/www.bbmri.it\/en\/wp-json\/wp\/v2\/users\/1"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/www.bbmri.it\/en\/wp-json\/wp\/v2\/comments?post=2018"
            }
        ],
        "version-history": [
            {
                "count": 4,
                "href": "https:\/\/www.bbmri.it\/en\/wp-json\/wp\/v2\/posts\/2018\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 2023,
                "href": "https:\/\/www.bbmri.it\/en\/wp-json\/wp\/v2\/posts\/2018\/revisions\/2023"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/www.bbmri.it\/en\/wp-json\/wp\/v2\/media\/22"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/www.bbmri.it\/en\/wp-json\/wp\/v2\/media?parent=2018"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "category",
                "embeddable": true,
                "href": "https:\/\/www.bbmri.it\/en\/wp-json\/wp\/v2\/categories?post=2018"
            },
            {
                "taxonomy": "post_tag",
                "embeddable": true,
                "href": "https:\/\/www.bbmri.it\/en\/wp-json\/wp\/v2\/tags?post=2018"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}